{"id":1799,"date":"2024-09-07T02:38:13","date_gmt":"2024-09-07T02:38:13","guid":{"rendered":"https:\/\/cmictamaulipas.org.mx\/?p=1799"},"modified":"2024-09-07T02:38:20","modified_gmt":"2024-09-07T02:38:20","slug":"visita-del-presidente-nacional-de-cmic-al-centro-de-entrenamiento-en-tamaulipas","status":"publish","type":"post","link":"https:\/\/cmictamaulipas.org.mx\/index.php\/2024\/09\/07\/visita-del-presidente-nacional-de-cmic-al-centro-de-entrenamiento-en-tamaulipas\/","title":{"rendered":"Visita del Presidente Nacional de CMIC al Centro de entrenamiento en Tamaulipas"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; column_structure=&#8221;1_3,2_3&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_3&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_gallery _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; gallery_ids=&#8221;1800,1802,1803,1804&#8243; posts_number=&#8221;2&#8243; show_title_and_caption=&#8221;off&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_gallery][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; type=&#8221;2_3&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Visita del Presidente Nacional de CMIC al Centro de entrenamiento en Tamaulipas<\/p>\n<p>El d\u00eda de hoy, 6 de septiembre, el Mtro. Luis Rafael M\u00e9ndez Jaled, Presidente Nacional de la C\u00e1mara Mexicana de la Industria de la Construcci\u00f3n (CMIC), realiz\u00f3 un recorrido por el Centro de Entrenamiento CMIC Tamaulipas, ubicado en el Parque de la Peque\u00f1a y Mediana Industria en Altamira, Tamaulipas.<\/p>\n<p>Durante la visita, fue acompa\u00f1ado por el Presidente de CMIC Tamaulipas, Pablo Eduardo Haro Panduro, as\u00ed como por miembros del Comit\u00e9 Directivo de la Delegaci\u00f3n Tamaulipas. El recorrido permiti\u00f3 a los asistentes conocer de primera mano las instalaciones que formar\u00e1n parte de este importante centro de formaci\u00f3n, cuyo objetivo es fortalecer las capacidades de los profesionales de la industria de la construcci\u00f3n en la regi\u00f3n.<\/p>\n<p>Este Centro de Entrenamiento se perfila como un pilar fundamental para la capacitaci\u00f3n y el desarrollo de las peque\u00f1as y medianas empresas en el sector, contribuyendo al crecimiento sostenible de la construcci\u00f3n en Tamaulipas.<\/p>\n<p>Agradecemos al Mtro. Luis Rafael M\u00e9ndez Jaled y a todos los asistentes por su compromiso con el desarrollo y la profesionalizaci\u00f3n de nuestra industria.<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/cmic?__eep__=6&amp;__cft__%5b0%5d=AZW-_ri4LGPVQoEzhoPIxyw49mXCWsiCCCSUN69cx-L2a2RF8JNwmEZnTPOX722Qh-Voyz1z-I96kqrAsv640xYbqZVE81_MinTof0YNpCr9X-7lfJN1_QscEv7MQl3Q3fz_rQNd2fJKwUV-w4RwMw1E5exVdsVov9Ls-ADi73DZBw&amp;__tn__=*NK-R\">#CMIC<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/cmictamaulipas?__eep__=6&amp;__cft__%5b0%5d=AZW-_ri4LGPVQoEzhoPIxyw49mXCWsiCCCSUN69cx-L2a2RF8JNwmEZnTPOX722Qh-Voyz1z-I96kqrAsv640xYbqZVE81_MinTof0YNpCr9X-7lfJN1_QscEv7MQl3Q3fz_rQNd2fJKwUV-w4RwMw1E5exVdsVov9Ls-ADi73DZBw&amp;__tn__=*NK-R\">#CMICTamaulipas<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/centrodeentrenamiento?__eep__=6&amp;__cft__%5b0%5d=AZW-_ri4LGPVQoEzhoPIxyw49mXCWsiCCCSUN69cx-L2a2RF8JNwmEZnTPOX722Qh-Voyz1z-I96kqrAsv640xYbqZVE81_MinTof0YNpCr9X-7lfJN1_QscEv7MQl3Q3fz_rQNd2fJKwUV-w4RwMw1E5exVdsVov9Ls-ADi73DZBw&amp;__tn__=*NK-R\">#CentroDeEntrenamiento<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/altamira?__eep__=6&amp;__cft__%5b0%5d=AZW-_ri4LGPVQoEzhoPIxyw49mXCWsiCCCSUN69cx-L2a2RF8JNwmEZnTPOX722Qh-Voyz1z-I96kqrAsv640xYbqZVE81_MinTof0YNpCr9X-7lfJN1_QscEv7MQl3Q3fz_rQNd2fJKwUV-w4RwMw1E5exVdsVov9Ls-ADi73DZBw&amp;__tn__=*NK-R\">#Altamira<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/capacitaci%C3%B3n?__eep__=6&amp;__cft__%5b0%5d=AZW-_ri4LGPVQoEzhoPIxyw49mXCWsiCCCSUN69cx-L2a2RF8JNwmEZnTPOX722Qh-Voyz1z-I96kqrAsv640xYbqZVE81_MinTof0YNpCr9X-7lfJN1_QscEv7MQl3Q3fz_rQNd2fJKwUV-w4RwMw1E5exVdsVov9Ls-ADi73DZBw&amp;__tn__=*NK-R\">#Capacitaci\u00f3n<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/desarrolloindustrial?__eep__=6&amp;__cft__%5b0%5d=AZW-_ri4LGPVQoEzhoPIxyw49mXCWsiCCCSUN69cx-L2a2RF8JNwmEZnTPOX722Qh-Voyz1z-I96kqrAsv640xYbqZVE81_MinTof0YNpCr9X-7lfJN1_QscEv7MQl3Q3fz_rQNd2fJKwUV-w4RwMw1E5exVdsVov9Ls-ADi73DZBw&amp;__tn__=*NK-R\">#DesarrolloIndustrial<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visita del Presidente Nacional de CMIC al Centro de entrenamiento en Tamaulipas El d\u00eda de hoy, 6 de septiembre, el Mtro. Luis Rafael M\u00e9ndez Jaled, Presidente Nacional de la C\u00e1mara Mexicana de la Industria de la Construcci\u00f3n (CMIC), realiz\u00f3 un recorrido por el Centro de Entrenamiento CMIC Tamaulipas, ubicado en el Parque de la Peque\u00f1a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1080","_joinchat":[],"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-eventos"],"_links":{"self":[{"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/1799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1799"}],"version-history":[{"count":2,"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/1799\/revisions"}],"predecessor-version":[{"id":1805,"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/posts\/1799\/revisions\/1805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/media\/1800"}],"wp:attachment":[{"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cmictamaulipas.org.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}